{"id":3602,"date":"2025-11-30T20:22:11","date_gmt":"2025-11-30T20:22:11","guid":{"rendered":"https:\/\/zupnija-menges.rkc.si\/?p=3602"},"modified":"2025-12-07T21:38:56","modified_gmt":"2025-12-07T21:38:56","slug":"oznanila-1-adventna-nedelja","status":"publish","type":"post","link":"https:\/\/zupnija-menges.rkc.si\/index.php\/2025\/11\/30\/oznanila-1-adventna-nedelja\/","title":{"rendered":"OZNANILA: 1. adventna nedelja"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/zupnija-menges.rkc.si\/wp-content\/uploads\/2025\/03\/prayer-2544994_1280-1024x686.jpg\" alt=\"\" class=\"wp-image-3319\" width=\"-48\" height=\"-32\" srcset=\"https:\/\/zupnija-menges.rkc.si\/wp-content\/uploads\/2025\/03\/prayer-2544994_1280-1024x686.jpg 1024w, https:\/\/zupnija-menges.rkc.si\/wp-content\/uploads\/2025\/03\/prayer-2544994_1280-300x201.jpg 300w, https:\/\/zupnija-menges.rkc.si\/wp-content\/uploads\/2025\/03\/prayer-2544994_1280-768x514.jpg 768w, https:\/\/zupnija-menges.rkc.si\/wp-content\/uploads\/2025\/03\/prayer-2544994_1280-1000x670.jpg 1000w, https:\/\/zupnija-menges.rkc.si\/wp-content\/uploads\/2025\/03\/prayer-2544994_1280-230x154.jpg 230w, https:\/\/zupnija-menges.rkc.si\/wp-content\/uploads\/2025\/03\/prayer-2544994_1280-350x234.jpg 350w, https:\/\/zupnija-menges.rkc.si\/wp-content\/uploads\/2025\/03\/prayer-2544994_1280-480x321.jpg 480w, https:\/\/zupnija-menges.rkc.si\/wp-content\/uploads\/2025\/03\/prayer-2544994_1280.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n<p>Za \u010di\u0161\u010denje cerkve se zahvaljujem skupini iz Topol in Dobena, prihodnjo soboto so na vrsti Pristava in Mali Menge\u0161, zahodno od Liparjeve. Iz\u0161la je prazni\u010dna \u0161tevilka Dru\u017eine, nova \u0161tevilka Ognji\u0161\u010da s koledarjem za prihodnje leto. Iz\u0161el je tudi nov <a href=\"https:\/\/zupnija-menges.rkc.si\/wp-content\/uploads\/2025\/11\/MENGES_MihaelovList-12-2025-int.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"> Mihaelov list.<\/a><\/p>\n\n\n\n<p>Danes ob 15.00 ima sre\u010danje skupina Vera in Lu\u010d v \u017eupnijskem domu.<\/p>\n\n\n\n<p>V torek od 17.00 do 18.00 bo molitev pred Najsvetej\u0161im.<\/p>\n\n\n\n<p>V sredo ob 19.30 bo v \u017eupnijskem domu seja \u017dPS.<\/p>\n\n\n\n<p>Od \u010detrtka do sobote bo molitev pred Najsvetej\u0161im od 17.00 do 18.00.<\/p>\n\n\n\n<p>V petek bo obisk bolnikov po domovih.<\/p>\n\n\n\n<p>V soboto od 7.00 do 8.30 bo vpis svetih ma\u0161 za januar in februar.<\/p>\n\n\n\n<p>V soboto \u0160kofijska gimnazija Vipava vabi na dan odprtih vrat. Program se pri\u010dne ob 8.45. Vabljeni u\u010denci in star\u0161i 8. in 9. razreda.<\/p>\n\n\n\n<p>Iz sobote na nedeljo bo celono\u010dno \u010de\u0161\u010denje pred Najsvetej\u0161im v kapeli v \u017eupni\u0161\u010du.<\/p>\n\n\n\n<p>Prihodnjo nedeljo bo pohod po Fundkovi poti. Pe\u0161 romanje se pri\u010dne ob 13.30 pri \u017eupnijski cerkvi. Ob 15.00 bodo v \u0160inkovem Turnu pete litanije in blagoslov z Najsvetej\u0161im. Ob 18.30 ima v \u017eupni\u0161\u010du sre\u010danje zakonska skupina.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"724\" height=\"1024\" src=\"https:\/\/zupnija-menges.rkc.si\/wp-content\/uploads\/2025\/12\/mase-47-25-724x1024.jpg\" alt=\"\" class=\"wp-image-3622\" srcset=\"https:\/\/zupnija-menges.rkc.si\/wp-content\/uploads\/2025\/12\/mase-47-25-724x1024.jpg 724w, https:\/\/zupnija-menges.rkc.si\/wp-content\/uploads\/2025\/12\/mase-47-25-212x300.jpg 212w, https:\/\/zupnija-menges.rkc.si\/wp-content\/uploads\/2025\/12\/mase-47-25-768x1086.jpg 768w, https:\/\/zupnija-menges.rkc.si\/wp-content\/uploads\/2025\/12\/mase-47-25-230x325.jpg 230w, https:\/\/zupnija-menges.rkc.si\/wp-content\/uploads\/2025\/12\/mase-47-25-350x495.jpg 350w, https:\/\/zupnija-menges.rkc.si\/wp-content\/uploads\/2025\/12\/mase-47-25-480x679.jpg 480w, https:\/\/zupnija-menges.rkc.si\/wp-content\/uploads\/2025\/12\/mase-47-25.jpg 794w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Za \u010di\u0161\u010denje cerkve se zahvaljujem skupini iz Topol in Dobena, prihodnjo soboto so na vrsti Pristava in Mali Menge\u0161, zahodno od Liparjeve. Iz\u0161la je prazni\u010dna \u0161tevilka Dru\u017eine, nova \u0161tevilka Ognji\u0161\u010da [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3319,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>OZNANILA: 1. adventna nedelja - \u017dupnija Menge\u0161<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zupnija-menges.rkc.si\/index.php\/2025\/11\/30\/oznanila-1-adventna-nedelja\/\" \/>\n<meta property=\"og:locale\" content=\"sl_SI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OZNANILA: 1. adventna nedelja - \u017dupnija Menge\u0161\" \/>\n<meta property=\"og:description\" content=\"Za \u010di\u0161\u010denje cerkve se zahvaljujem skupini iz Topol in Dobena, prihodnjo soboto so na vrsti Pristava in Mali Menge\u0161, zahodno od Liparjeve. Iz\u0161la je prazni\u010dna \u0161tevilka Dru\u017eine, nova \u0161tevilka Ognji\u0161\u010da [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zupnija-menges.rkc.si\/index.php\/2025\/11\/30\/oznanila-1-adventna-nedelja\/\" \/>\n<meta property=\"og:site_name\" content=\"\u017dupnija Menge\u0161\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-30T20:22:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-07T21:38:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zupnija-menges.rkc.si\/wp-content\/uploads\/2025\/03\/prayer-2544994_1280.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"857\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u017dupnija Menge\u0161\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u017dupnija Menge\u0161\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/zupnija-menges.rkc.si\/index.php\/2025\/11\/30\/oznanila-1-adventna-nedelja\/\",\"url\":\"https:\/\/zupnija-menges.rkc.si\/index.php\/2025\/11\/30\/oznanila-1-adventna-nedelja\/\",\"name\":\"OZNANILA: 1. adventna nedelja - \u017dupnija Menge\u0161\",\"isPartOf\":{\"@id\":\"https:\/\/zupnija-menges.rkc.si\/#website\"},\"datePublished\":\"2025-11-30T20:22:11+00:00\",\"dateModified\":\"2025-12-07T21:38:56+00:00\",\"author\":{\"@id\":\"https:\/\/zupnija-menges.rkc.si\/#\/schema\/person\/30a6136b3e62fe0948bbeadab6a011c8\"},\"breadcrumb\":{\"@id\":\"https:\/\/zupnija-menges.rkc.si\/index.php\/2025\/11\/30\/oznanila-1-adventna-nedelja\/#breadcrumb\"},\"inLanguage\":\"sl-SI\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/zupnija-menges.rkc.si\/index.php\/2025\/11\/30\/oznanila-1-adventna-nedelja\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/zupnija-menges.rkc.si\/index.php\/2025\/11\/30\/oznanila-1-adventna-nedelja\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/zupnija-menges.rkc.si\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"OZNANILA: 1. adventna nedelja\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/zupnija-menges.rkc.si\/#website\",\"url\":\"https:\/\/zupnija-menges.rkc.si\/\",\"name\":\"\u017dupnija Menge\u0161\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/zupnija-menges.rkc.si\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"sl-SI\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/zupnija-menges.rkc.si\/#\/schema\/person\/30a6136b3e62fe0948bbeadab6a011c8\",\"name\":\"\u017dupnija Menge\u0161\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sl-SI\",\"@id\":\"https:\/\/zupnija-menges.rkc.si\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5ab28e97e020e17154731a602459bd9e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5ab28e97e020e17154731a602459bd9e?s=96&d=mm&r=g\",\"caption\":\"\u017dupnija Menge\u0161\"},\"url\":\"https:\/\/zupnija-menges.rkc.si\/index.php\/author\/zumenges\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OZNANILA: 1. adventna nedelja - \u017dupnija Menge\u0161","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zupnija-menges.rkc.si\/index.php\/2025\/11\/30\/oznanila-1-adventna-nedelja\/","og_locale":"sl_SI","og_type":"article","og_title":"OZNANILA: 1. adventna nedelja - \u017dupnija Menge\u0161","og_description":"Za \u010di\u0161\u010denje cerkve se zahvaljujem skupini iz Topol in Dobena, prihodnjo soboto so na vrsti Pristava in Mali Menge\u0161, zahodno od Liparjeve. Iz\u0161la je prazni\u010dna \u0161tevilka Dru\u017eine, nova \u0161tevilka Ognji\u0161\u010da [&hellip;]","og_url":"https:\/\/zupnija-menges.rkc.si\/index.php\/2025\/11\/30\/oznanila-1-adventna-nedelja\/","og_site_name":"\u017dupnija Menge\u0161","article_published_time":"2025-11-30T20:22:11+00:00","article_modified_time":"2025-12-07T21:38:56+00:00","og_image":[{"width":1280,"height":857,"url":"https:\/\/zupnija-menges.rkc.si\/wp-content\/uploads\/2025\/03\/prayer-2544994_1280.jpg","type":"image\/jpeg"}],"author":"\u017dupnija Menge\u0161","twitter_card":"summary_large_image","twitter_misc":{"Written by":"\u017dupnija Menge\u0161"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zupnija-menges.rkc.si\/index.php\/2025\/11\/30\/oznanila-1-adventna-nedelja\/","url":"https:\/\/zupnija-menges.rkc.si\/index.php\/2025\/11\/30\/oznanila-1-adventna-nedelja\/","name":"OZNANILA: 1. adventna nedelja - \u017dupnija Menge\u0161","isPartOf":{"@id":"https:\/\/zupnija-menges.rkc.si\/#website"},"datePublished":"2025-11-30T20:22:11+00:00","dateModified":"2025-12-07T21:38:56+00:00","author":{"@id":"https:\/\/zupnija-menges.rkc.si\/#\/schema\/person\/30a6136b3e62fe0948bbeadab6a011c8"},"breadcrumb":{"@id":"https:\/\/zupnija-menges.rkc.si\/index.php\/2025\/11\/30\/oznanila-1-adventna-nedelja\/#breadcrumb"},"inLanguage":"sl-SI","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zupnija-menges.rkc.si\/index.php\/2025\/11\/30\/oznanila-1-adventna-nedelja\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/zupnija-menges.rkc.si\/index.php\/2025\/11\/30\/oznanila-1-adventna-nedelja\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/zupnija-menges.rkc.si\/"},{"@type":"ListItem","position":2,"name":"OZNANILA: 1. adventna nedelja"}]},{"@type":"WebSite","@id":"https:\/\/zupnija-menges.rkc.si\/#website","url":"https:\/\/zupnija-menges.rkc.si\/","name":"\u017dupnija Menge\u0161","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zupnija-menges.rkc.si\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"sl-SI"},{"@type":"Person","@id":"https:\/\/zupnija-menges.rkc.si\/#\/schema\/person\/30a6136b3e62fe0948bbeadab6a011c8","name":"\u017dupnija Menge\u0161","image":{"@type":"ImageObject","inLanguage":"sl-SI","@id":"https:\/\/zupnija-menges.rkc.si\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5ab28e97e020e17154731a602459bd9e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5ab28e97e020e17154731a602459bd9e?s=96&d=mm&r=g","caption":"\u017dupnija Menge\u0161"},"url":"https:\/\/zupnija-menges.rkc.si\/index.php\/author\/zumenges\/"}]}},"_links":{"self":[{"href":"https:\/\/zupnija-menges.rkc.si\/index.php\/wp-json\/wp\/v2\/posts\/3602"}],"collection":[{"href":"https:\/\/zupnija-menges.rkc.si\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zupnija-menges.rkc.si\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zupnija-menges.rkc.si\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/zupnija-menges.rkc.si\/index.php\/wp-json\/wp\/v2\/comments?post=3602"}],"version-history":[{"count":4,"href":"https:\/\/zupnija-menges.rkc.si\/index.php\/wp-json\/wp\/v2\/posts\/3602\/revisions"}],"predecessor-version":[{"id":3623,"href":"https:\/\/zupnija-menges.rkc.si\/index.php\/wp-json\/wp\/v2\/posts\/3602\/revisions\/3623"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zupnija-menges.rkc.si\/index.php\/wp-json\/wp\/v2\/media\/3319"}],"wp:attachment":[{"href":"https:\/\/zupnija-menges.rkc.si\/index.php\/wp-json\/wp\/v2\/media?parent=3602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zupnija-menges.rkc.si\/index.php\/wp-json\/wp\/v2\/categories?post=3602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zupnija-menges.rkc.si\/index.php\/wp-json\/wp\/v2\/tags?post=3602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}